{"id":37829,"date":"2025-06-02T17:49:06","date_gmt":"2025-06-02T17:49:06","guid":{"rendered":"https:\/\/new.igihe.com\/french\/Traite-d-etres-humains-plus-de-100-Rwandais-rapatries-en-un-an-37829\/"},"modified":"2025-06-02T17:47:55","modified_gmt":"2025-06-02T17:47:55","slug":"Traite-d-etres-humains-plus-de-100-Rwandais-rapatries-en-un-an","status":"publish","type":"post","link":"https:\/\/new.igihe.com\/french\/Traite-d-etres-humains-plus-de-100-Rwandais-rapatries-en-un-an\/","title":{"rendered":"Traite d\u2019\u00eatres humains : plus de 100 Rwandais rapatri\u00e9s en un an"},"content":{"rendered":"<p>Les donn\u00e9es ont \u00e9t\u00e9 rendues publiques lors d\u2019une conf\u00e9rence de presse tenue ce 2 juin 2025, au cours de laquelle le RIB a fait le point sur la situation du trafic d\u2019\u00eatres humains au Rwanda.<\/p>\n<p>Cette annonce fait suite au rapatriement, le 23 avril 2025, de dix citoyens rwandais qui avaient \u00e9t\u00e9 envoy\u00e9s en Birmanie pour y \u00eatre exploit\u00e9s. Par ailleurs, cinq autres ressortissants sont toujours port\u00e9s disparus et activement recherch\u00e9s en vue de leur retour.<\/p>\n<p>Le porte-parole du RIB, le Dr Thierry Murangira, a pr\u00e9cis\u00e9 que, parmi les 57 personnes intercept\u00e9es avant d\u2019\u00eatre livr\u00e9es aux r\u00e9seaux de traite, 52 \u00e9taient des femmes et seulement 5 des hommes, ce ph\u00e9nom\u00e8ne s\u2019expliquant principalement par le fait que les femmes sont les premi\u00e8res victimes d\u2019exploitation sexuelle.<\/p>\n<p>Le Dr Murangira a \u00e9galement soulign\u00e9 le nombre consid\u00e9rable de personnes intercept\u00e9es avant d\u2019\u00eatre vendues \u00e0 l\u2019\u00e9tranger. : entre juillet 2023 et juin 2024, 39 individus ont \u00e9t\u00e9 prot\u00e9g\u00e9s des r\u00e9seaux de trafiquants, insistant sur le fait que la gravit\u00e9 du fl\u00e9au ne se mesure pas au nombre de cas recens\u00e9s.<\/p>\n<p>\u00ab L\u2019ampleur du ph\u00e9nom\u00e8ne ne se mesure pas au nombre de victimes : m\u00eame une seule personne exploit\u00e9e constitue un drame majeur. Aucun \u00eatre humain ne doit jamais \u00eatre trait\u00e9 comme une marchandise \u00bb, a-t-il d\u00e9clar\u00e9.<\/p>\n<p>\u00ab Ce probl\u00e8me doit \u00eatre consid\u00e9r\u00e9 comme une forme de d\u00e9shumanisation, o\u00f9 la victime est r\u00e9duite \u00e0 un simple objet ou produit utilis\u00e9 au profit d\u2019autrui \u00bb, a-t-il ajout\u00e9.<\/p>\n<p>Le porte-parole du RIB a appel\u00e9 \u00e0 renforcer la coop\u00e9ration, d\u00e9non\u00e7ant l\u2019implication consciente de certains proches dans les m\u00e9canismes de recrutement.<\/p>\n<p>\u00ab Certains parents ou membres de famille facilitent d\u00e9lib\u00e9r\u00e9ment l\u2019envoi de leurs proches vers ces r\u00e9seaux \u00bb, a-t-il regrett\u00e9.<\/p>\n<p>Dans d\u2019autres cas, un obstacle psychologique important complique les efforts de lutte contre cette traite : beaucoup de victimes per\u00e7oivent les avertissements qui leur sont faits comme un frein \u00e0 une opportunit\u00e9, persuad\u00e9es qu\u2019elles vont rencontrer un partenaire id\u00e9al \u00e0 l\u2019\u00e9tranger ou d\u00e9crocher un emploi prometteur.<\/p>\n<p>Bien que plusieurs des personnes rapatri\u00e9es ou intercept\u00e9es aient transit\u00e9 par le Rwanda, le Dr Murangira a tenu \u00e0 pr\u00e9ciser que le pays ne constitue pas une base op\u00e9rationnelle pour les r\u00e9seaux de traite. Il serait plut\u00f4t utilis\u00e9 comme zone de passage par des trafiquants venus de pays voisins.<\/p>\n<p>\u00ab Il n\u2019existe pas de r\u00e9seaux de traite organis\u00e9s op\u00e9rant depuis le Rwanda. Toutefois, il arrive que des personnes en provenance de pays voisins y transitent. D\u00e8s qu\u2019un tel cas est signal\u00e9, il est imm\u00e9diatement d\u00e9mantel\u00e9. Par ailleurs, le Rwanda s\u2019investit activement dans le rapatriement des victimes afin de leur assurer un retour en toute s\u00e9curit\u00e9 \u00bb, a-t-il soulign\u00e9.<\/p>\n<p>Le Dr Murangira a \u00e9galement attir\u00e9 l\u2019attention sur d\u2019autres formes de criminalit\u00e9 \u00e9troitement li\u00e9es \u00e0 la traite d&#8217;\u00eatres humains, citant \u00e0 titre d\u2019exemple, la d\u00e9couverte en 2024 \u00e0 Kigali d\u2019un \u00e9tablissement nocturne o\u00f9 des femmes se produisaient nues.<\/p>\n<p>\u00ab Il s\u2019agissait manifestement d\u2019une forme d\u2019exploitation sexuelle au profit d\u2019autrui. L\u2019\u00c9tat ne saurait tol\u00e9rer de telles d\u00e9rives, et la population doit les signaler sans la moindre h\u00e9sitation \u00bb, a-t-il soulign\u00e9.<\/p>\n<p>Enfin, le RIB a exhort\u00e9 les citoyens \u00e0 faire preuve de vigilance face aux promesses d\u2019opportunit\u00e9s \u00e0 l\u2019\u00e9tranger, notamment lorsqu\u2019elles \u00e9manent de personnes inconnues ou qu\u2019aucun motif cr\u00e9dible ne justifie le fait d\u2019avoir \u00e9t\u00e9 s\u00e9lectionn\u00e9 pour en b\u00e9n\u00e9ficier.<\/p>\n<figure class=\"spip-document spip-document-61924 aligncenter\"><img decoding=\"async\" src=\"https:\/\/fr.igihe.com\/IMG\/jpg\/r1-9.jpg\" alt=\"Le Bureau d\u2019Investigation du Rwanda a indiqu\u00e9 qu\u2019entre juin 2024 et mai 2025, 105 citoyens rwandais avaient \u00e9t\u00e9 rapatri\u00e9s de diff\u00e9rents pays o\u00f9 ils avaient \u00e9t\u00e9 victimes de traite d\u2019\u00eatres humains\" \/><\/figure>\n<figure class=\"spip-document spip-document-61923 aligncenter\"><img decoding=\"async\" src=\"https:\/\/fr.igihe.com\/IMG\/jpg\/r2-10.jpg\" alt=\"Le Dr Murangira a soulign\u00e9 une nette augmentation du nombre de personnes intercept\u00e9es avant d\u2019\u00eatre vendues \u00e0 l\u2019\u00e9tranger \" \/><\/figure>\n<figure class=\"spip-document spip-document-61922 aligncenter\"><img decoding=\"async\" src=\"https:\/\/fr.igihe.com\/IMG\/jpg\/r3-9.jpg\" alt=\"Les donn\u00e9es ont \u00e9t\u00e9 rendues publiques lors d\u2019une conf\u00e9rence de presse tenue ce 2 juin 2025\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Le Bureau d\u2019Investigation du Rwanda (RIB) a indiqu\u00e9 qu&#8217;entre juin 2024 et mai 2025, 105 citoyens rwandais ont \u00e9t\u00e9 rapatri\u00e9s de diff\u00e9rents pays o\u00f9 ils avaient \u00e9t\u00e9 victimes de traite d&#8217;\u00eatres humains. Dans le m\u00eame temps, 75 autres personnes ont \u00e9t\u00e9 intercept\u00e9es avant d\u2019\u00eatre livr\u00e9es \u00e0 ce r\u00e9seau criminel transnational.<\/p>\n","protected":false},"author":488,"featured_media":4000061921,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7587],"tags":[7605],"byline":[7717],"hashtag":[],"class_list":["post-37829","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-justice","tag-homenews","byline-igihe"],"bylines":[{"id":7717,"name":"IGIHE","slug":"igihe","description":"","image":{"id":0,"url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&f=y&r=g","alt":"Default avatar","title":"Default avatar","caption":"","mime_type":"image\/jpeg","sizes":[]},"user_id":393}],"contributors":[{"id":7717,"name":"IGIHE","slug":"igihe","description":"","image":{"id":0,"url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&f=y&r=g","alt":"Default avatar","title":"Default avatar","caption":"","mime_type":"image\/jpeg","sizes":[]},"user_id":393}],"featured_image":{"id":4000061921,"url":"https:\/\/fr-images.igihe.com\/IMG\/logo\/cp-81.jpg","alt":"","caption":"","mime_type":"image\/jpeg","width":0,"height":0,"sizes":{"thumbnail":{"url":"https:\/\/fr-images.igihe.com\/IMG\/logo\/cp-81.jpg","width":1,"height":1},"medium":{"url":"https:\/\/fr-images.igihe.com\/IMG\/logo\/cp-81.jpg","width":1,"height":1},"medium_large":{"url":"https:\/\/fr-images.igihe.com\/IMG\/logo\/cp-81.jpg","width":1,"height":1},"large":{"url":"https:\/\/fr-images.igihe.com\/IMG\/logo\/cp-81.jpg","width":1,"height":1},"full":{"url":"https:\/\/fr-images.igihe.com\/IMG\/logo\/cp-81.jpg","width":0,"height":0}}},"_links":{"self":[{"href":"https:\/\/new.igihe.com\/french\/wp-json\/wp\/v2\/posts\/37829","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.igihe.com\/french\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.igihe.com\/french\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.igihe.com\/french\/wp-json\/wp\/v2\/users\/488"}],"replies":[{"embeddable":true,"href":"https:\/\/new.igihe.com\/french\/wp-json\/wp\/v2\/comments?post=37829"}],"version-history":[{"count":0,"href":"https:\/\/new.igihe.com\/french\/wp-json\/wp\/v2\/posts\/37829\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/new.igihe.com\/french\/wp-json\/wp\/v2\/media\/4000061921"}],"wp:attachment":[{"href":"https:\/\/new.igihe.com\/french\/wp-json\/wp\/v2\/media?parent=37829"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.igihe.com\/french\/wp-json\/wp\/v2\/categories?post=37829"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.igihe.com\/french\/wp-json\/wp\/v2\/tags?post=37829"},{"taxonomy":"byline","embeddable":true,"href":"https:\/\/new.igihe.com\/french\/wp-json\/wp\/v2\/byline?post=37829"},{"taxonomy":"hashtag","embeddable":true,"href":"https:\/\/new.igihe.com\/french\/wp-json\/wp\/v2\/hashtag?post=37829"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}