{"id":37804,"date":"2025-05-30T16:43:06","date_gmt":"2025-05-30T16:43:06","guid":{"rendered":"https:\/\/new.igihe.com\/french\/Le-Rwanda-et-la-Tanzanie-renforcent-leur-cooperation-militaire-transfrontaliere-37804\/"},"modified":"2025-05-30T16:42:30","modified_gmt":"2025-05-30T16:42:30","slug":"Le-Rwanda-et-la-Tanzanie-renforcent-leur-cooperation-militaire-transfrontaliere","status":"publish","type":"post","link":"https:\/\/new.igihe.com\/french\/Le-Rwanda-et-la-Tanzanie-renforcent-leur-cooperation-militaire-transfrontaliere\/","title":{"rendered":"Le Rwanda et la Tanzanie renforcent leur coop\u00e9ration militaire transfrontali\u00e8re"},"content":{"rendered":"<p>Les discussions ont port\u00e9 sur l\u2019\u00e9valuation des progr\u00e8s accomplis depuis la derni\u00e8re session, mettant en avant les efforts conjoints d\u00e9ploy\u00e9s pour lutter contre les activit\u00e9s ill\u00e9gales et renforcer la s\u00e9curit\u00e9 dans les communaut\u00e9s frontali\u00e8res.<\/p>\n<p>Les deux d\u00e9l\u00e9gations ont r\u00e9affirm\u00e9 leur engagement commun \u00e0 maintenir une coop\u00e9ration \u00e9troite par le biais d\u2019initiatives concert\u00e9es, afin de faire face aux menaces \u00e9mergentes. Elles ont \u00e9galement salu\u00e9 les avanc\u00e9es notables r\u00e9alis\u00e9es sous la direction de leurs Chefs d\u2019\u00c9tat respectifs.<\/p>\n<p>Dans son discours d\u2019ouverture, le G\u00e9n\u00e9ral de brigade Pascal Muhizi, commandant de la 5\u1d49 division d\u2019infanterie des RDF, a exprim\u00e9 sa profonde gratitude envers les Chefs d\u2019\u00c9tat du Rwanda et de la Tanzanie pour leur leadership visionnaire, leur engagement constant en faveur de la paix et leur soutien d\u00e9terminant \u00e0 l\u2019int\u00e9gration r\u00e9gionale.<\/p>\n<p>Il a soulign\u00e9 que cette volont\u00e9 politique, port\u00e9e par le leadership des plus hautes autorit\u00e9s, a cr\u00e9\u00e9 un cadre favorable \u00e0 une coop\u00e9ration militaire efficace entre les deux nations. Le G\u00e9n\u00e9ral de brigade Muhizi a rappel\u00e9 aux commandants que la paix et la s\u00e9curit\u00e9 le long de la fronti\u00e8re constituent une responsabilit\u00e9 collective. Il les a encourag\u00e9s \u00e0 demeurer vigilants et \u00e0 adopter une d\u00e9marche proactive dans la gestion des menaces.<\/p>\n<p>Il a insist\u00e9 sur la n\u00e9cessit\u00e9 d\u2019intensifier la vigilance face aux menaces transfrontali\u00e8res, notamment le terrorisme et les activit\u00e9s \u00e9conomiques ill\u00e9gales, susceptibles de d\u00e9stabiliser les r\u00e9gions frontali\u00e8res si elles ne sont pas ma\u00eetris\u00e9es. <\/p>\n<p>De son c\u00f4t\u00e9, le G\u00e9n\u00e9ral de brigade Gabriel Elias Kwiligwa, commandant de la 202\u1d49 brigade d\u2019infanterie des TPDF et chef de la d\u00e9l\u00e9gation tanzanienne, a salu\u00e9 les avanc\u00e9es significatives obtenues lors des r\u00e9unions pr\u00e9c\u00e9dentes dans la r\u00e9solution des divers d\u00e9fis s\u00e9curitaires.<\/p>\n<p>Il a attribu\u00e9 ces progr\u00e8s en mati\u00e8re de paix et d\u2019harmonie \u00e0 la confiance mutuelle, \u00e0 la transparence et \u00e0 la compr\u00e9hension partag\u00e9e entre les deux forces arm\u00e9es. Selon lui, ces piliers fondamentaux ont contribu\u00e9 \u00e0 renforcer durablement la s\u00e9curit\u00e9 au profit des populations vivant le long de la fronti\u00e8re.<\/p>\n<p>En marge de la r\u00e9union, la d\u00e9l\u00e9gation conjointe a rendu visite aux autorit\u00e9s du district de Kirehe, o\u00f9 le maire Bruno Rangira les a chaleureusement accueillis. La visite s\u2019est ensuite poursuivie dans la zone frontali\u00e8re de Karushuga, situ\u00e9e \u00e0 c\u00f4t\u00e9 du district tanzanien de Kaisho, lui-m\u00eame proche de Ngara.<\/p>\n<figure class=\"spip-document spip-document-61708 aligncenter\"><img decoding=\"async\" src=\"https:\/\/fr.igihe.com\/IMG\/jpg\/t3-6.jpg\" alt=\"Les Forces de d\u00e9fense du Rwanda (RDF) et de Tanzanie (TPDF) ont tenu la 12\u1d49 R\u00e9union de s\u00e9curit\u00e9 des commandants de proximit\u00e9\" \/><\/figure>\n<figure class=\"spip-document spip-document-61710 aligncenter\"><img decoding=\"async\" src=\"https:\/\/fr.igihe.com\/IMG\/jpg\/t1-6.jpg\" alt=\"Les discussions ont port\u00e9 sur le renforcement de la coop\u00e9ration militaire et les moyens de r\u00e9pondre aux d\u00e9fis s\u00e9curitaires le long de la fronti\u00e8re commune\" \/><\/figure>\n<figure class=\"spip-document spip-document-61709 aligncenter\"><img decoding=\"async\" src=\"https:\/\/fr.igihe.com\/IMG\/jpg\/t2-6.jpg\" alt=\"Les deux d\u00e9l\u00e9gations ont r\u00e9affirm\u00e9 leur engagement commun \u00e0 maintenir une coop\u00e9ration \u00e9troite par le biais d\u2019initiatives concert\u00e9es\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Les Forces de d\u00e9fense du Rwanda (RDF) et de Tanzanie (TPDF) ont tenu, du 28 au 30 mai, la 12\u1d49 R\u00e9union de s\u00e9curit\u00e9 des commandants de proximit\u00e9 \u00e0 Nyagatare, dans l\u2019Est du Rwanda. Les discussions ont port\u00e9 sur le renforcement de la coop\u00e9ration militaire et les moyens de r\u00e9pondre aux d\u00e9fis s\u00e9curitaires le long de la fronti\u00e8re commune.<\/p>\n","protected":false},"author":488,"featured_media":4000061707,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7540],"tags":[7605],"byline":[7717],"hashtag":[],"class_list":["post-37804","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-securite","tag-homenews","byline-igihe"],"bylines":[{"id":7717,"name":"IGIHE","slug":"igihe","description":"","image":{"id":0,"url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&f=y&r=g","alt":"Default avatar","title":"Default avatar","caption":"","mime_type":"image\/jpeg","sizes":[]},"user_id":393}],"contributors":[{"id":7717,"name":"IGIHE","slug":"igihe","description":"","image":{"id":0,"url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&f=y&r=g","alt":"Default avatar","title":"Default avatar","caption":"","mime_type":"image\/jpeg","sizes":[]},"user_id":393}],"featured_image":{"id":4000061707,"url":"https:\/\/fr-images.igihe.com\/IMG\/logo\/cp-75.jpg","alt":"","caption":"","mime_type":"image\/jpeg","width":0,"height":0,"sizes":{"thumbnail":{"url":"https:\/\/fr-images.igihe.com\/IMG\/logo\/cp-75.jpg","width":1,"height":1},"medium":{"url":"https:\/\/fr-images.igihe.com\/IMG\/logo\/cp-75.jpg","width":1,"height":1},"medium_large":{"url":"https:\/\/fr-images.igihe.com\/IMG\/logo\/cp-75.jpg","width":1,"height":1},"large":{"url":"https:\/\/fr-images.igihe.com\/IMG\/logo\/cp-75.jpg","width":1,"height":1},"full":{"url":"https:\/\/fr-images.igihe.com\/IMG\/logo\/cp-75.jpg","width":0,"height":0}}},"_links":{"self":[{"href":"https:\/\/new.igihe.com\/french\/wp-json\/wp\/v2\/posts\/37804","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.igihe.com\/french\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.igihe.com\/french\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.igihe.com\/french\/wp-json\/wp\/v2\/users\/488"}],"replies":[{"embeddable":true,"href":"https:\/\/new.igihe.com\/french\/wp-json\/wp\/v2\/comments?post=37804"}],"version-history":[{"count":0,"href":"https:\/\/new.igihe.com\/french\/wp-json\/wp\/v2\/posts\/37804\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/new.igihe.com\/french\/wp-json\/wp\/v2\/media\/4000061707"}],"wp:attachment":[{"href":"https:\/\/new.igihe.com\/french\/wp-json\/wp\/v2\/media?parent=37804"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.igihe.com\/french\/wp-json\/wp\/v2\/categories?post=37804"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.igihe.com\/french\/wp-json\/wp\/v2\/tags?post=37804"},{"taxonomy":"byline","embeddable":true,"href":"https:\/\/new.igihe.com\/french\/wp-json\/wp\/v2\/byline?post=37804"},{"taxonomy":"hashtag","embeddable":true,"href":"https:\/\/new.igihe.com\/french\/wp-json\/wp\/v2\/hashtag?post=37804"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}