{"id":37787,"date":"2025-05-29T16:58:03","date_gmt":"2025-05-29T16:58:03","guid":{"rendered":"https:\/\/new.igihe.com\/french\/La-RDC-entre-cendres-et-concessions-37787\/"},"modified":"2025-05-29T16:52:37","modified_gmt":"2025-05-29T16:52:37","slug":"La-RDC-entre-cendres-et-concessions","status":"publish","type":"post","link":"https:\/\/new.igihe.com\/french\/La-RDC-entre-cendres-et-concessions\/","title":{"rendered":"La RDC entre cendres et concessions"},"content":{"rendered":"<p>Tandis que la grande coalition militaro-insurrectionnelle compos\u00e9e des FARDC, des combattants FDLR, des groupes dits wazalendo, ainsi que des troupes burundaises et des forces de la SADC ont  essuy\u00e9es une d\u00e9b\u00e2cle strat\u00e9gique face \u00e0 la pouss\u00e9e inexorable des forces de l\u2019AFC\/M23, et que les villes n\u00e9vralgiques de Goma et de Bukavu ont bascul\u00e9es lentement vers une incertitude pesante et un effondrement logistique jusqu\u2019\u00e0 l\u2019arriv\u00e9e des hommes du G\u00e9n\u00e9ral Makenga dans les deux villes d\u00e9sormais sous leur contr\u00f4le. <\/p>\n<p>A Kinshasa, le pouvoir central chancelle, en proie \u00e0 une d\u00e9sagr\u00e9gation institutionnelle inqui\u00e9tante. La sc\u00e8ne politique, disloqu\u00e9e par les luttes intestines, peine \u00e0 articuler un discours de souverainet\u00e9 coh\u00e9rent, tandis que la cacophonie r\u00e8gne au sommet de l\u2019\u00c9tat. Et pourtant, au c\u0153ur de cette tourmente nationale, un ballet feutr\u00e9 de n\u00e9gociations s\u2019intensifie, r\u00e9v\u00e9lant le visage impassible d\u2019une realpolitik implacable.<\/p>\n<p>En effet, malgr\u00e9 l\u2019\u00e9tat de guerre latent, les gouvernements de Kigali et de Kinshasa poursuivent discr\u00e8tement mais r\u00e9solument des pourparlers relatifs \u00e0 de juteux accords environnementaux, \u00e9nerg\u00e9tiques et miniers, sous la m\u00e9diation active du D\u00e9partement d\u2019\u00c9tat am\u00e9ricain. <\/p>\n<p>Du c\u00f4t\u00e9 rwandais, un protocole d\u2019accord aurait d\u2019ores et d\u00e9j\u00e0 \u00e9t\u00e9 sign\u00e9, consacrant ainsi une avance diplomatique dans ce bras de fer \u00e9conomique o\u00f9 l\u2019influence prime sur la l\u00e9gitimit\u00e9. A Kinshasa, les tractations continuent, port\u00e9es \u00e0 la fois par les canaux classiques du minist\u00e8re des Affaires \u00e9trang\u00e8res et par le truchement de relais strat\u00e9giques install\u00e9s \u00e0 Washington. Parmi ces derniers, le cabinet Von Batten-Montague-York, sp\u00e9cialis\u00e9 dans le lobbying et le conseil d\u2019influence, joue un r\u00f4le pivot dans la tentative congolaise de capter les faveurs du Congr\u00e8s am\u00e9ricain et d\u2019attirer les investisseurs priv\u00e9s.<\/p>\n<p>L\u2019accord en gestation d\u00e9passe de loin les enjeux locaux du Katanga ou du Kivu : il s\u2019agit d\u2019une entreprise tentaculaire visant l\u2019ouverture de vastes segments du sous-sol congolais \u00e0 l\u2019exploration industrielle, dans un cadre contractuel qui pourrait s\u2019\u00e9tendre sur plusieurs d\u00e9cennies. Kinshasa cherche \u00e0 imposer une clause de transformation locale des mati\u00e8res premi\u00e8res, revendiquant ainsi une forme de r\u00e9habilitation \u00e9conomique par la cr\u00e9ation d\u2019une cha\u00eene de valeur sur son propre territoire. Toutefois, cette exigence, bien que louable en principe, demeure encore incertaine dans son application concr\u00e8te, notamment \u00e0 court terme, face aux r\u00e9ticences structurelles des investisseurs \u00e9trangers.<\/p>\n<p>La Premi\u00e8re ministre congolaise est attendue aux \u00c9tats-Unis pour mener une op\u00e9ration de s\u00e9duction \u00e9conomique, destin\u00e9e \u00e0 rassurer les milieux d\u2019affaires quant \u00e0 la stabilit\u00e9 au moins apparente du pays, et \u00e0 promouvoir les potentialit\u00e9s inexplor\u00e9es de son sol, malgr\u00e9 le chaos r\u00e9gnant.<\/p>\n<p>Dans ce contexte, un dilemme moral et g\u00e9opolitique se dessine avec une acuit\u00e9 troublante : peut-on construire un avenir \u00e9conomique durable sur les ruines d\u2019une souverainet\u00e9 \u00e9corn\u00e9e ? La diplomatie actuelle, si elle n\u2019est pas encadr\u00e9e avec rigueur et transparence, risque fort de perp\u00e9tuer les logiques pr\u00e9datrices qui, depuis des d\u00e9cennies, r\u00e9duisent le Congo \u00e0 une mine ouverte sous tutelle \u00e9trang\u00e8re, plut\u00f4t qu\u2019\u00e0 une nation\u00a0\u00e9mancip\u00e9e.<\/p>\n<figure class=\"spip-document spip-document-61666 aligncenter\"><img decoding=\"async\" src=\"https:\/\/fr.igihe.com\/IMG\/jpg\/sum-5.jpg\" alt=\"Alors que l\u2019Est de la RDC traverse une grave crise s\u00e9curitaire, une \u00e9trange man\u0153uvre diplomatique se trame en coulisses\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Alors m\u00eame que l\u2019Est de la R\u00e9publique d\u00e9mocratique du Congo est en proie \u00e0 l\u2019un des \u00e9pisodes les plus graves de d\u00e9litement s\u00e9curitaire depuis les guerres qui ont ravag\u00e9 la r\u00e9gion au tournant du mill\u00e9naire, une \u00e9trange partition diplomatique se joue dans les coulisses du pouvoir. <\/p>\n","protected":false},"author":488,"featured_media":4000061665,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7544],"tags":[7605],"byline":[9102],"hashtag":[],"class_list":["post-37787","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politique","tag-homenews","byline-tite-gatabazi"],"bylines":[{"id":9102,"name":"Tite Gatabazi","slug":"tite-gatabazi","description":"","image":{"id":0,"url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&f=y&r=g","alt":"Default avatar","title":"Default avatar","caption":"","mime_type":"image\/jpeg","sizes":[]},"user_id":472}],"contributors":[{"id":9102,"name":"Tite Gatabazi","slug":"tite-gatabazi","description":"","image":{"id":0,"url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&f=y&r=g","alt":"Default avatar","title":"Default avatar","caption":"","mime_type":"image\/jpeg","sizes":[]},"user_id":472}],"featured_image":{"id":4000061665,"url":"https:\/\/fr-images.igihe.com\/IMG\/logo\/sum_cp-4.jpg","alt":"","caption":"","mime_type":"image\/jpeg","width":0,"height":0,"sizes":{"thumbnail":{"url":"https:\/\/fr-images.igihe.com\/IMG\/logo\/sum_cp-4.jpg","width":1,"height":1},"medium":{"url":"https:\/\/fr-images.igihe.com\/IMG\/logo\/sum_cp-4.jpg","width":1,"height":1},"medium_large":{"url":"https:\/\/fr-images.igihe.com\/IMG\/logo\/sum_cp-4.jpg","width":1,"height":1},"large":{"url":"https:\/\/fr-images.igihe.com\/IMG\/logo\/sum_cp-4.jpg","width":1,"height":1},"full":{"url":"https:\/\/fr-images.igihe.com\/IMG\/logo\/sum_cp-4.jpg","width":0,"height":0}}},"_links":{"self":[{"href":"https:\/\/new.igihe.com\/french\/wp-json\/wp\/v2\/posts\/37787","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.igihe.com\/french\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.igihe.com\/french\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.igihe.com\/french\/wp-json\/wp\/v2\/users\/488"}],"replies":[{"embeddable":true,"href":"https:\/\/new.igihe.com\/french\/wp-json\/wp\/v2\/comments?post=37787"}],"version-history":[{"count":0,"href":"https:\/\/new.igihe.com\/french\/wp-json\/wp\/v2\/posts\/37787\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/new.igihe.com\/french\/wp-json\/wp\/v2\/media\/4000061665"}],"wp:attachment":[{"href":"https:\/\/new.igihe.com\/french\/wp-json\/wp\/v2\/media?parent=37787"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.igihe.com\/french\/wp-json\/wp\/v2\/categories?post=37787"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.igihe.com\/french\/wp-json\/wp\/v2\/tags?post=37787"},{"taxonomy":"byline","embeddable":true,"href":"https:\/\/new.igihe.com\/french\/wp-json\/wp\/v2\/byline?post=37787"},{"taxonomy":"hashtag","embeddable":true,"href":"https:\/\/new.igihe.com\/french\/wp-json\/wp\/v2\/hashtag?post=37787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}