{"id":1108,"date":"2012-01-12T16:52:59","date_gmt":"2012-01-12T16:52:59","guid":{"rendered":"https:\/\/new.igihe.com\/french\/bugesera-la-population-mise-en-garde-contre-les-1108\/"},"modified":"2014-07-04T13:58:33","modified_gmt":"2014-07-04T13:58:33","slug":"bugesera-la-population-mise-en-garde-contre-les","status":"publish","type":"post","link":"https:\/\/new.igihe.com\/french\/bugesera-la-population-mise-en-garde-contre-les\/","title":{"rendered":"Bugesera: La population mise en garde contre les crocodiles des lacs"},"content":{"rendered":"<p>Les autorit\u00e9s du district de Bugesera ont mis en garde les gens qui font la p\u00eache ill\u00e9gale dans la rivi\u00e8re de Ririma suite \u00e0 une augmentation des attaques de crocodiles de la rivi\u00e8re.<\/p>\n<p>Ce mardi un villageois du nom de Valens Ndayambaje a \u00e9t\u00e9 attaqu\u00e9 par un crocodile au moment o\u00f9 il allait puiser de l\u2019eau, il a \u00e9t\u00e9 gri\u00e8vement bless\u00e9s et \u00e9vacu\u00e9 vers le centre de sant\u00e9 dans un centre de sant\u00e9 \u00e0 proximit\u00e9.<\/p>\n<p>Les p\u00e9cheurs ill\u00e9gaux font la p\u00eache sans pirogue pour camoufler leurs identit\u00e9s et cela les exposes aux attaques des crocodiles, tandis que les p\u00e9cheurs l\u00e9gaux sont enregistr\u00e9s et regroup\u00e9s au sein des coop\u00e9ratives mais aussi ils p\u00eachent avec des barques sophistiqu\u00e9s qui les prot\u00e8gent contres les assauts des crocodiles.&nbsp;<\/p>\n<p>Le secr\u00e9taire ex\u00e9cutif du secteur de Kimaranzara bordant la rivi\u00e8re, Jean-Pierre Gasaba, conseille aux habitants d\u2019\u00eatre tr\u00e8s vigilants en allant puiser de l\u2019eau \u00e0 la rivi\u00e8re.<\/p>\n<p>Il a condamn\u00e9 l\u2019attitude de la convoitise d\u2019argent remarqu\u00e9 chez les p\u00eacheurs ill\u00e9gaux, qui vont \u00e0 la rivi\u00e8re sans mesures de protection et vendent les poissons sans payer d\u2019imp\u00f4ts.<\/p>\n<p>Balthazar Hicuburundi, un p\u00eacheur clandestin&nbsp;: \u00ab&nbsp;Oui l\u2019argent de la contrebande est facile et rapide, mais nos vies sont en danger, nous travaillons par la gr\u00e2ce de Dieu, sinon nous serions disparus depuis longtemps comme certains de nos amis. Nos familles sont toujours pr\u00eats pour les mauvaises nouvelles&nbsp;\u00bb, a-t il fait remarquer.<\/p>\n<p>Les attaques des crocodiles sont devenues tr\u00e8s fr\u00e9quents dans les lacs de Bugesera.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les autorit\u00e9s du district de Bugesera ont mis en garde les gens qui font la p\u00eache ill\u00e9gale dans la rivi\u00e8re de Ririma suite \u00e0 une augmentation des attaques de crocodiles de la rivi\u00e8re. Ce mardi un villageois du nom de Valens Ndayambaje a \u00e9t\u00e9 attaqu\u00e9 par un crocodile au moment o\u00f9 il allait puiser de [&hellip;]<\/p>\n","protected":false},"author":456,"featured_media":4000031530,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7543],"tags":[7605],"byline":[7696],"hashtag":[],"class_list":["post-1108","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-securite-17","tag-homenews","byline-olivier-kabalisa"],"bylines":[{"id":7696,"name":"Olivier Kabalisa","slug":"olivier-kabalisa","description":"","image":{"id":0,"url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&f=y&r=g","alt":"Default avatar","title":"Default avatar","caption":"","mime_type":"image\/jpeg","sizes":[]},"user_id":null}],"contributors":[{"id":7696,"name":"Olivier Kabalisa","slug":"olivier-kabalisa","description":"","image":{"id":0,"url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&f=y&r=g","alt":"Default avatar","title":"Default avatar","caption":"","mime_type":"image\/jpeg","sizes":[]},"user_id":null}],"featured_image":{"id":4000031530,"url":"https:\/\/fr-images.igihe.com\/IMG\/logo\/arton1108.jpg","alt":"","caption":"","mime_type":"image\/jpeg","width":0,"height":0,"sizes":{"thumbnail":{"url":"https:\/\/fr-images.igihe.com\/IMG\/logo\/arton1108.jpg","width":1,"height":1},"medium":{"url":"https:\/\/fr-images.igihe.com\/IMG\/logo\/arton1108.jpg","width":1,"height":1},"medium_large":{"url":"https:\/\/fr-images.igihe.com\/IMG\/logo\/arton1108.jpg","width":1,"height":1},"large":{"url":"https:\/\/fr-images.igihe.com\/IMG\/logo\/arton1108.jpg","width":1,"height":1},"full":{"url":"https:\/\/fr-images.igihe.com\/IMG\/logo\/arton1108.jpg","width":0,"height":0}}},"_links":{"self":[{"href":"https:\/\/new.igihe.com\/french\/wp-json\/wp\/v2\/posts\/1108","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.igihe.com\/french\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.igihe.com\/french\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.igihe.com\/french\/wp-json\/wp\/v2\/users\/456"}],"replies":[{"embeddable":true,"href":"https:\/\/new.igihe.com\/french\/wp-json\/wp\/v2\/comments?post=1108"}],"version-history":[{"count":0,"href":"https:\/\/new.igihe.com\/french\/wp-json\/wp\/v2\/posts\/1108\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/new.igihe.com\/french\/wp-json\/wp\/v2\/media\/4000031530"}],"wp:attachment":[{"href":"https:\/\/new.igihe.com\/french\/wp-json\/wp\/v2\/media?parent=1108"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.igihe.com\/french\/wp-json\/wp\/v2\/categories?post=1108"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.igihe.com\/french\/wp-json\/wp\/v2\/tags?post=1108"},{"taxonomy":"byline","embeddable":true,"href":"https:\/\/new.igihe.com\/french\/wp-json\/wp\/v2\/byline?post=1108"},{"taxonomy":"hashtag","embeddable":true,"href":"https:\/\/new.igihe.com\/french\/wp-json\/wp\/v2\/hashtag?post=1108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}